{"id":991,"date":"2022-09-08T07:40:25","date_gmt":"2022-09-08T07:40:25","guid":{"rendered":"https:\/\/echteboter.com\/?post_type=recepten&#038;p=991"},"modified":"2023-01-26T11:50:23","modified_gmt":"2023-01-26T11:50:23","slug":"echte-kruidenboter","status":"publish","type":"recepten","link":"https:\/\/echteboter.com\/en\/recepten\/echte-boter-herbs\/","title":{"rendered":"Echte Boter herb butter"},"content":{"rendered":"<p><span style=\"font-weight: 400;\"><strong>Method: herb butter<\/strong><\/span><\/p>\n<ol>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Allow butter to come to room temperature\u00a0<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Beat the butter in a mixer till creamy\u00a0<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Chop the chives and parsley fine\u00a0<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Crush the garlic\u00a0<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Add the herbs and garlic to the the Echte Boter\u00a0<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Add pepper to taste\u00a0<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Mix well\u00a0<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Serve in a dish with French bread or on grilled meat<br \/>\n<\/span><\/li>\n<\/ol>\n<p><strong><br \/>\nMethod: curried herb butter<\/strong><\/p>\n<ol>\n<li>Allow butter to come to room temperature<\/li>\n<li>Beat the butter in a mixer till creamy<\/li>\n<li>Mix the curry powder with a little water to make a paste<\/li>\n<li>Add the paste to the butter<\/li>\n<li>Add pepper to taste<\/li>\n<li>Chop the chives fine<\/li>\n<li>Add to the herb butter<\/li>\n<li>Mix well<\/li>\n<li>Serve in a dish with French bread or on grilled meat<\/li>\n<\/ol>\n<p><strong><br \/>\nMethod: Italian herb butter<\/strong><\/p>\n<ol>\n<li>Allow butter to come to room temperature<\/li>\n<li>Beat the butter in a mixer till creamy<\/li>\n<li>Put the sundried tomatoes, pine-nuts, red basil, garlic and lemon juice in a food processor and pulse to a fine consistency<\/li>\n<li>Add the paste to the butter<\/li>\n<li>Add the cheese<\/li>\n<li>Add pepper to taste<\/li>\n<li>Mix well<\/li>\n<li>Serve in a dish with French bread or on grilled meat<\/li>\n<\/ol>","protected":false},"excerpt":{"rendered":"<p>Use our versatile butter to make the tastiest herb butters to accompany drinks or a barbeque in the garden. We have come up with three - slightly different - types of herb butter for you, because with our Echte Boter you will keep on spreading!<\/p>","protected":false},"featured_media":2265,"template":"","class_list":["post-991","recepten","type-recepten","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Echte (kruiden)boter - Echte Boter<\/title>\n<meta name=\"description\" content=\"Echte (kruiden)boter! Drie keer - net even anders- soorten kruidenboter, lekker bij de borrel of BBQ... met onze Echte Boter blijf je smeren!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/echteboter.com\/en\/recepten\/echte-boter-herbs\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Echte (kruiden)boter - Echte Boter\" \/>\n<meta property=\"og:description\" content=\"Echte (kruiden)boter! Drie keer - net even anders- soorten kruidenboter, lekker bij de borrel of BBQ... met onze Echte Boter blijf je smeren!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/echteboter.com\/en\/recepten\/echte-boter-herbs\/\" \/>\n<meta property=\"og:site_name\" content=\"Echte Boter\" \/>\n<meta property=\"article:modified_time\" content=\"2023-01-26T11:50:23+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/echteboter.com\/wp-content\/uploads\/2022\/10\/Website_recept_454x300_kruidenboter-e1674733812658.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"454\" \/>\n\t<meta property=\"og:image:height\" content=\"300\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/echteboter.com\\\/recepten\\\/echte-kruidenboter\\\/\",\"url\":\"https:\\\/\\\/echteboter.com\\\/recepten\\\/echte-kruidenboter\\\/\",\"name\":\"Echte (kruiden)boter - Echte Boter\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/echteboter.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/echteboter.com\\\/recepten\\\/echte-kruidenboter\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/echteboter.com\\\/recepten\\\/echte-kruidenboter\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/echteboter.com\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/Website_recept_454x300_kruidenboter-e1674733812658.jpg\",\"datePublished\":\"2022-09-08T07:40:25+00:00\",\"dateModified\":\"2023-01-26T11:50:23+00:00\",\"description\":\"Echte (kruiden)boter! Drie keer - net even anders- soorten kruidenboter, lekker bij de borrel of BBQ... met onze Echte Boter blijf je smeren!\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/echteboter.com\\\/recepten\\\/echte-kruidenboter\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/echteboter.com\\\/recepten\\\/echte-kruidenboter\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/echteboter.com\\\/recepten\\\/echte-kruidenboter\\\/#primaryimage\",\"url\":\"https:\\\/\\\/echteboter.com\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/Website_recept_454x300_kruidenboter-e1674733812658.jpg\",\"contentUrl\":\"https:\\\/\\\/echteboter.com\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/Website_recept_454x300_kruidenboter-e1674733812658.jpg\",\"width\":454,\"height\":300},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/echteboter.com\\\/recepten\\\/echte-kruidenboter\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/echteboter.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Echte (kruiden)boter\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/echteboter.com\\\/#website\",\"url\":\"https:\\\/\\\/echteboter.com\\\/\",\"name\":\"Echte Boter\",\"description\":\"Er kan er maar \u00e9\u00e9n de echte zijn!\",\"publisher\":{\"@id\":\"https:\\\/\\\/echteboter.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/echteboter.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/echteboter.com\\\/#organization\",\"name\":\"Echte Boter\",\"url\":\"https:\\\/\\\/echteboter.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/echteboter.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/echteboter.com\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/echteboter-wit_logo.svg\",\"contentUrl\":\"https:\\\/\\\/echteboter.com\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/echteboter-wit_logo.svg\",\"width\":191.62,\"height\":72.97,\"caption\":\"Echte Boter\"},\"image\":{\"@id\":\"https:\\\/\\\/echteboter.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Echte Boter herb butter","description":"Echte Boter herb butter. We have come up with three - slightly different - types of herb butter for you!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/echteboter.com\/en\/recepten\/echte-boter-herbs\/","og_locale":"en_GB","og_type":"article","og_title":"Echte (kruiden)boter - Echte Boter","og_description":"Echte (kruiden)boter! Drie keer - net even anders- soorten kruidenboter, lekker bij de borrel of BBQ... met onze Echte Boter blijf je smeren!","og_url":"https:\/\/echteboter.com\/en\/recepten\/echte-boter-herbs\/","og_site_name":"Echte Boter","article_modified_time":"2023-01-26T11:50:23+00:00","og_image":[{"width":454,"height":300,"url":"https:\/\/echteboter.com\/wp-content\/uploads\/2022\/10\/Website_recept_454x300_kruidenboter-e1674733812658.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Estimated reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/echteboter.com\/recepten\/echte-kruidenboter\/","url":"https:\/\/echteboter.com\/recepten\/echte-kruidenboter\/","name":"Echte Boter herb butter","isPartOf":{"@id":"https:\/\/echteboter.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/echteboter.com\/recepten\/echte-kruidenboter\/#primaryimage"},"image":{"@id":"https:\/\/echteboter.com\/recepten\/echte-kruidenboter\/#primaryimage"},"thumbnailUrl":"https:\/\/echteboter.com\/wp-content\/uploads\/2022\/10\/Website_recept_454x300_kruidenboter-e1674733812658.jpg","datePublished":"2022-09-08T07:40:25+00:00","dateModified":"2023-01-26T11:50:23+00:00","description":"Echte Boter herb butter. We have come up with three - slightly different - types of herb butter for you!","breadcrumb":{"@id":"https:\/\/echteboter.com\/recepten\/echte-kruidenboter\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/echteboter.com\/recepten\/echte-kruidenboter\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/echteboter.com\/recepten\/echte-kruidenboter\/#primaryimage","url":"https:\/\/echteboter.com\/wp-content\/uploads\/2022\/10\/Website_recept_454x300_kruidenboter-e1674733812658.jpg","contentUrl":"https:\/\/echteboter.com\/wp-content\/uploads\/2022\/10\/Website_recept_454x300_kruidenboter-e1674733812658.jpg","width":454,"height":300},{"@type":"BreadcrumbList","@id":"https:\/\/echteboter.com\/recepten\/echte-kruidenboter\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/echteboter.com\/"},{"@type":"ListItem","position":2,"name":"Echte (kruiden)boter"}]},{"@type":"WebSite","@id":"https:\/\/echteboter.com\/#website","url":"https:\/\/echteboter.com\/","name":"Echte Boter","description":"The one and only!","publisher":{"@id":"https:\/\/echteboter.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/echteboter.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/echteboter.com\/#organization","name":"Echte Boter","url":"https:\/\/echteboter.com\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/echteboter.com\/#\/schema\/logo\/image\/","url":"https:\/\/echteboter.com\/wp-content\/uploads\/2023\/01\/echteboter-wit_logo.svg","contentUrl":"https:\/\/echteboter.com\/wp-content\/uploads\/2023\/01\/echteboter-wit_logo.svg","width":191.62,"height":72.97,"caption":"Echte Boter"},"image":{"@id":"https:\/\/echteboter.com\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/echteboter.com\/en\/wp-json\/wp\/v2\/recepten\/991","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/echteboter.com\/en\/wp-json\/wp\/v2\/recepten"}],"about":[{"href":"https:\/\/echteboter.com\/en\/wp-json\/wp\/v2\/types\/recepten"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/echteboter.com\/en\/wp-json\/wp\/v2\/media\/2265"}],"wp:attachment":[{"href":"https:\/\/echteboter.com\/en\/wp-json\/wp\/v2\/media?parent=991"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}